{"id":95,"count":1,"description":"","link":"https:\/\/cristian-perez.com\/en\/tag\/programacion-2\/","name":"programming","slug":"programacion-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>programacion archivos - Cristian Perez<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cristian-perez.com\/en\/tag\/programacion-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"programacion archivos - Cristian Perez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cristian-perez.com\/en\/tag\/programacion-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Cristian Perez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/cristian-perez.com\\\/tag\\\/programacion-2\\\/\",\"url\":\"https:\\\/\\\/cristian-perez.com\\\/tag\\\/programacion-2\\\/\",\"name\":\"programacion archivos - Cristian Perez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cristian-perez.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cristian-perez.com\\\/tag\\\/programacion-2\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cristian-perez.com\\\/tag\\\/programacion-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/cristian-perez.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"programacion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cristian-perez.com\\\/#website\",\"url\":\"https:\\\/\\\/cristian-perez.com\\\/\",\"name\":\"Cristian Perez\",\"description\":\"Aprendiendo y securizando\",\"publisher\":{\"@id\":\"https:\\\/\\\/cristian-perez.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cristian-perez.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/cristian-perez.com\\\/#organization\",\"name\":\"Cristian Perez\",\"url\":\"https:\\\/\\\/cristian-perez.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/cristian-perez.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/cristian-perez.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-yo002.png\",\"contentUrl\":\"https:\\\/\\\/cristian-perez.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/cropped-yo002.png\",\"width\":612,\"height\":612,\"caption\":\"Cristian Perez\"},\"image\":{\"@id\":\"https:\\\/\\\/cristian-perez.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"programacion archivos - Cristian Perez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cristian-perez.com\/en\/tag\/programacion-2\/","og_locale":"en_GB","og_type":"article","og_title":"programacion archivos - Cristian Perez","og_url":"https:\/\/cristian-perez.com\/en\/tag\/programacion-2\/","og_site_name":"Cristian Perez","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cristian-perez.com\/tag\/programacion-2\/","url":"https:\/\/cristian-perez.com\/tag\/programacion-2\/","name":"programacion archivos - Cristian Perez","isPartOf":{"@id":"https:\/\/cristian-perez.com\/#website"},"breadcrumb":{"@id":"https:\/\/cristian-perez.com\/tag\/programacion-2\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/cristian-perez.com\/tag\/programacion-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/cristian-perez.com\/"},{"@type":"ListItem","position":2,"name":"programacion"}]},{"@type":"WebSite","@id":"https:\/\/cristian-perez.com\/#website","url":"https:\/\/cristian-perez.com\/","name":"Christian Perez","description":"Learning and securizing","publisher":{"@id":"https:\/\/cristian-perez.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cristian-perez.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/cristian-perez.com\/#organization","name":"Christian Perez","url":"https:\/\/cristian-perez.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/cristian-perez.com\/#\/schema\/logo\/image\/","url":"https:\/\/cristian-perez.com\/wp-content\/uploads\/2023\/03\/cropped-yo002.png","contentUrl":"https:\/\/cristian-perez.com\/wp-content\/uploads\/2023\/03\/cropped-yo002.png","width":612,"height":612,"caption":"Cristian Perez"},"image":{"@id":"https:\/\/cristian-perez.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cristian-perez.com\/en\/wp-json\/wp\/v2\/tags\/95","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cristian-perez.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/cristian-perez.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/cristian-perez.com\/en\/wp-json\/wp\/v2\/posts?tags=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}